{"id":774,"date":"2025-03-06T09:39:35","date_gmt":"2025-03-06T09:39:35","guid":{"rendered":"https:\/\/grossetulln.at\/?p=774"},"modified":"2025-03-06T10:07:12","modified_gmt":"2025-03-06T10:07:12","slug":"revierinformationen-saison-2025","status":"publish","type":"post","link":"https:\/\/grossetulln.at\/index.php\/2025\/03\/06\/revierinformationen-saison-2025\/","title":{"rendered":"Revierinformationen Saison 2025 &#8211; Mythos Wienerwaldforelle &#8211; die Legende lebt!"},"content":{"rendered":"\n<p><strong>Liebe Freunde der Grossen Tulln,<\/strong><\/p>\n\n\n\n<p>das Altjahresfischen ist gef\u00fchlt erst ein paar Wochen vorbei, und schon steht die neue Saison vor der T\u00fcre.<\/p>\n\n\n\n<p><strong>Das Revier \u00f6ffnet auch heuer wieder am 16. M\u00e4rz.<\/strong><\/p>\n\n\n\n<p>Die gute Nachricht: Auch heuer kann ich f\u00fcr bestehende Lizenznehmer die Jahreskarte ausnahmsweise um den halben Preis anbieten.&nbsp;<\/p>\n\n\n\n<p>Die Jahresgeb\u00fchr f\u00fcr<strong> bestehende Lizenznehmer und Jugendlizenznehmer betr\u00e4gt 300.<\/strong>-, der Normalpreis 600.- Euro. (Kontonummer: (IBAN) AT44 3266 7000 0074 0043)<\/p>\n\n\n\n<p>Am Donnerstag den 13. M\u00e4rz werden <strong>150 Kilo Regenbogenforellen<\/strong> (put&amp;take) ausgesetzt. Wer dabei sein will, wir treffen uns um 15 Uhr beim Wehr hinter dem Sportplatz in Neulengbach.<\/p>\n\n\n\n<p>Die Reduktion der Lizenzgeb\u00fchr wird deshalb ausnahmsweise verl\u00e4ngert, weil die Bachforelle in der Saison 2025 ganzj\u00e4hrig geschont bleibt.&nbsp;Dieser Schritt ist sorgsam gepr\u00fcft und auf Rat namhafter Experten und auf Basis von Studien gesetzt worden.<\/p>\n\n\n\n<p><strong>Aus Gr\u00fcnden der Transparenz m\u00f6chte ich die drei wichtigsten Argumente kurz skizzieren:<\/strong><\/p>\n\n\n\n<p>Nach der G\u00fcllepest im Jahr 2023 gab es im Juni 2024 eine Fischbestandserhebung durch das B\u00fcro \u201eProfisch\u201c (Dr. Michael Schabuss) Zwei Stellen im Oberlauf des Laabenbaches und drei Stellen im Anzbach wurden elektrisch abgefischt (Foto unten). An allen f\u00fcnf Stellen hat sich gezeigt, dass nur sehr wenige laichf\u00e4hige Exemplare in den Oberl\u00e4ufen vorhanden sind.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7521-1024x768.jpg\" alt=\"\" class=\"wp-image-779\" srcset=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7521-1024x768.jpg 1024w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7521-300x225.jpg 300w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7521-768x576.jpg 768w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7521-1536x1152.jpg 1536w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7521-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Das Hochwasser im September 2024 kostete weitere wertvolle Fischleben. W\u00e4hrend der Flut suchten tausende Fische Schutz in ruhigeren \u00dcberflutungszonen, als das Wasser zur\u00fcckging verendeten tausende Forellen in G\u00e4rten, auf \u00c4ckern und in Pf\u00fctzen. Wir haben so gut wie m\u00f6glich versucht (Auch mit Hilfe von Anrainern und E-Befischungen &#8211; Foto unten) zu retten was zu retten ist &#8211; es war aber ein Tropfen auf den heissen Stein.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8679-1024x768.jpg\" alt=\"\" class=\"wp-image-778\" srcset=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8679-1024x768.jpg 1024w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8679-300x225.jpg 300w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8679-768x576.jpg 768w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8679-1536x1152.jpg 1536w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8679-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Die gute Nachricht: Wir haben eine Genetik-Untersuchung der Bachforellen durch die&nbsp; Karl Franzens Universit\u00e4t in Graz beauftragt.&nbsp; Beim Ergebnis kann man von einer kleinen Sensation sprechen. <strong>Es gibt noch genetische \u201eUrst\u00e4mme\u201c der Bachforelle im Revier<\/strong>. Von 30 getesteten Bachforellen waren rund die H\u00e4lfte noch mit starken Hinweisen auf Genmaterial aus der Donau gekennzeichnet. 3 Exemplare wiesen eindeutig reine donaust\u00e4mmige Gene auf. Das hei\u00dft, rund 10% der Forellen in unserem Revier sind nicht vermischt und die H\u00e4lfte tragen die wichtigen Geninformationen, die ihnen ein Leben unter unseren Bedingungen erm\u00f6glichen. Ein Ergebnis, das starke Beweise f\u00fcr den Mythos der &#8222;Wienerwaldforelle &#8220; die sich seit Jahrtausenden an die Bedingungen in unserer Region angepasst hat, liefert! <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7528-1024x768.jpg\" alt=\"\" class=\"wp-image-777\" srcset=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7528-1024x768.jpg 1024w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7528-300x225.jpg 300w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7528-768x576.jpg 768w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7528-1536x1152.jpg 1536w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_7528-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Laut Dr. Steven Weiss, der Dutzende Untersuchungen dieser Art in \u00d6sterreich durchgef\u00fchrt hat ist das sehr ungew\u00f6hnlich. N\u00f6rdlich der Alpen findet man sonst fast ausschlie\u00dflich Genmaterial der atlantisch-st\u00e4mmigen Bachforellen. <\/p>\n\n\n\n<p><strong>Unser Revier stellt daher eine sehr rare Besonderheit dar.<\/strong><\/p>\n\n\n\n<p>Laut einhelliger Meinung aller befragten Experten ist zwischenzeitliche <strong>Schonung dieser wertvollen Forellen<\/strong> in Kombination mit weiteren <strong>Verbesserungen des Lebensraumes<\/strong> die beste M\u00f6glichkeit, diese wertvolle Population \u00fcber diese Krise zu retten und vom Aussterben zu bewahren. Von k\u00fcnstlicher Aufzucht des Genmaterials ist aufgrund der geringen Aussichten auf Erfolg laut Experten vorerst abzuraten, da diese einen sehr schwerwiegenden Eingriff in die ohnehin geschw\u00e4chte Population darstellt.<\/p>\n\n\n\n<p>Als <strong>Kompensation<\/strong> f\u00fcr die geschonten Bachforellen, werden deshalb die oben erw\u00e4hnten <strong>put&amp;take Regenbogenforellen<\/strong> f\u00fcr erfolgreiche Angelerlebnisse sorgen. Auch die Wanderung der Donaufische in unser Revier steht bevor. Sie wird wieder tolle Angelerlebnisse auf die &#8222;Donauriesen&#8220; Barbe, Nase, Russnase, Hecht und Barsch garantieren. <\/p>\n\n\n\n<p><strong>Ich w\u00fcrde mich sehr freuen, wenn Ihr diese Entscheidung, die Bachforelle zu schonen,  mittragt und ich Euch in diesem Jahr wieder im Revier begr\u00fc\u00dfen darf<\/strong>!<\/p>\n\n\n\n<p>F\u00fcr angeregte Gespr\u00e4che und Informationen, w\u00e4re die Lizenzvergabe am 14. M\u00e4rz im Stadtcafe gedacht. Alle bestehenden Lizenznehmer die die Lizenzgeb\u00fchr bis dahin bezahlt haben, bekommen ihre Lizenz an Ort und Stelle. Kontonummer: (IBAN) AT44 3266 7000 0074 0043<\/p>\n\n\n\n<p>Neue Interessenten bitte ich um Kontaktaufnahme (siehe Kontakt)<\/p>\n\n\n\n<p>Nach dem schwierigen Jahr 2024 m\u00f6chte ich aber noch eine <strong>positive Abschlussbilanz<\/strong> ziehen. Kollege Martin M\u00fchlbauer hat zwischen Anzbachm\u00fcndung und Siegersdorf eine Kartierung der Forellen-Laichpl\u00e4tze durchgef\u00fchrt. An 11 Stellen waren im Vorjahr noch Forrellen aktiv beim Laichen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"873\" height=\"1024\" src=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/Unknown-3-873x1024.jpeg\" alt=\"\" class=\"wp-image-775\" srcset=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/Unknown-3-873x1024.jpeg 873w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/Unknown-3-256x300.jpeg 256w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/Unknown-3-768x901.jpeg 768w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/Unknown-3.jpeg 1080w\" sizes=\"auto, (max-width: 873px) 100vw, 873px\" \/><\/figure>\n\n\n\n<p>Mit viel Durchsetzungskraft und Z\u00e4higkeit ist es auch gelungen, das Wasser in der Zeit bis zum Schlupf weitesgehend frei von Verunreinigungen durch Bauarbeiten zu halten. Der Wasserstand im Winter war gut, nach allen Regeln der Kunst m\u00fcssten dieser Tage <strong>tausende gesunde Jungfische geschl\u00fcpft<\/strong> sein.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8913-1024x768.jpg\" alt=\"\" class=\"wp-image-776\" srcset=\"https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8913-1024x768.jpg 1024w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8913-300x225.jpg 300w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8913-768x576.jpg 768w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8913-1536x1152.jpg 1536w, https:\/\/grossetulln.at\/wp-content\/uploads\/2025\/03\/IMG_8913-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Beim Altjahresangeln hatte ich nach drei W\u00fcrfen diese pr\u00e4chtige Bachforelle am Haken.Ich will nicht esoterisch abdriften, aber f\u00fcr mich war das fast wie ein Zeichen.&nbsp;Der Fluss lebt, er ist z\u00e4her als wir alle glauben und mit unserer Hilfe werden diese wunderbaren Tiere auch noch in hunderten Jahren leben und sich vermehren.&nbsp;<\/p>\n\n\n\n<p>Liebe Gr\u00fc\u00dfe,<\/p>\n\n\n\n<p>Ossi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Freunde der Grossen Tulln, das Altjahresfischen ist gef\u00fchlt erst ein paar Wochen vorbei, und schon steht die neue Saison vor der T\u00fcre. Das Revier \u00f6ffnet auch heuer wieder am 16. M\u00e4rz. Die gute Nachricht: Auch heuer kann ich f\u00fcr bestehende Lizenznehmer die Jahreskarte ausnahmsweise um den halben Preis anbieten.&nbsp; Die Jahresgeb\u00fchr f\u00fcr bestehende Lizenznehmer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/posts\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/comments?post=774"}],"version-history":[{"count":2,"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/posts\/774\/revisions"}],"predecessor-version":[{"id":783,"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/posts\/774\/revisions\/783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/media\/777"}],"wp:attachment":[{"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/media?parent=774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/categories?post=774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grossetulln.at\/index.php\/wp-json\/wp\/v2\/tags?post=774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}